{"id":1310,"date":"2016-10-12T12:10:57","date_gmt":"2016-10-12T11:10:57","guid":{"rendered":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/"},"modified":"2025-03-15T16:34:47","modified_gmt":"2025-03-15T15:34:47","slug":"blaesergitter-60-mm-4-rings","status":"publish","type":"product","link":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/","title":{"rendered":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet"},"content":{"rendered":"<p>BL\u00c6SERGITTER med 4 RINGS til bl\u00e6ser p\u00e5 <a href=\"https:\/\/solcelle.dk\/wordpress\/produkt\/sunon-ventilator12v-dc-60x60x15-1-5w-44-8-m3-h\/\">60\u00d760 MM<\/a>.<\/p>\n<p>&#8211; Til bl\u00e6ser p\u00e5 60\u00d760 MM.<br \/>\n&#8211; Antal ring: 6 RINGS.<br \/>\n&#8211; ring afstand: 5 \u00b1 1mm<br \/>\n&#8211; Material: forkromet<br \/>\n&#8211; Der f\u00f8lger ingen <a href=\"https:\/\/solcelle.dk\/wordpress\/produkt\/4xselvskaerende-skruer-5x10-til-sunon-blaeser\/\">skruer<\/a> med.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer<br \/>\nTil bl\u00e6ser p\u00e5 60&#215;60 MM<br \/>\nAntal ring: 4 RINGS<\/p>\n<p>Levering:\u00a01-2 dage<\/p>\n","protected":false},"featured_media":1308,"template":"","meta":{"_predictive_search_focuskw":"","_ps_exclude_item":""},"product_brand":[],"product_cat":[61],"product_tag":[],"class_list":["post-1310","product","type-product","status-publish","has-post-thumbnail","product_cat-tilbehoer-til-ventilation","product_shipping_class-forsendelse","post","post-with-thumbnail","post-with-thumbnail-large","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer Til bl\u00e6ser p\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\u00f8r til ventilation og solvarme kit\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A\" \/>\n\t<meta name=\"msvalidate.01\" content=\"1AF1F6665E665386B40B0E1A7011D221\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"da_DK\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Solcelle.dk | Online Webshop sol &amp; vindenergi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet\" \/>\n\t\t<meta property=\"og:description\" content=\"Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer Til bl\u00e6ser p\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\u00f8r til ventilation og solvarme kit\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-10-12T11:10:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-15T15:34:47+00:00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"position\":2,\"name\":\"Online solar PV shop \\\/ Solcelle webshop\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/#listItem\",\"name\":\"Forbrug, LEDlys, k\\u00f8l, pumper, ventilation\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/#listItem\",\"position\":3,\"name\":\"Forbrug, LEDlys, k\\u00f8l, pumper, ventilation\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/#listItem\",\"name\":\"Solcelleventilation, solvarme og frisk luft\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/#listItem\",\"position\":4,\"name\":\"Solcelleventilation, solvarme og frisk luft\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/tilbehoer-til-ventilation\\\/#listItem\",\"name\":\"Tilbeh\\u00f8r til ventilation og solvarme kit\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/#listItem\",\"name\":\"Forbrug, LEDlys, k\\u00f8l, pumper, ventilation\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/tilbehoer-til-ventilation\\\/#listItem\",\"position\":5,\"name\":\"Tilbeh\\u00f8r til ventilation og solvarme kit\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/tilbehoer-til-ventilation\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#listItem\",\"name\":\"BL\\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/#listItem\",\"name\":\"Solcelleventilation, solvarme og frisk luft\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#listItem\",\"position\":6,\"name\":\"BL\\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/lys-koeleskab-pumper-ventilator\\\/solvarme-ventilation\\\/tilbehoer-til-ventilation\\\/#listItem\",\"name\":\"Tilbeh\\u00f8r til ventilation og solvarme kit\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#itempage\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/\",\"name\":\"BL\\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet\",\"description\":\"Metalisk fingerbeskyttelsen fastg\\u00f8res med 4 skruer Til bl\\u00e6ser p\\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\\u00f8r til ventilation og solvarme kit\",\"inLanguage\":\"da-DK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/BL\\u00c6SERGITTER-med-ring.jpg\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#mainImage\",\"width\":250,\"height\":250,\"caption\":\"BL\\u00c6SERGITTER 92 MM 6 RINGS\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#mainImage\"},\"datePublished\":\"2016-10-12T12:10:57+01:00\",\"dateModified\":\"2025-03-15T16:34:47+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\",\"name\":\"Solcelle.dk, Sol & vind energi\",\"description\":\"Online Webshop sol & vindenergi\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"telephone\":\"+4541674467\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Solcelledk_Logo_144.png\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#organizationLogo\",\"width\":144,\"height\":144,\"caption\":\"Solcelle.dk Online webshop\"},\"image\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/blaesergitter-60-mm-4-rings\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"name\":\"Solcelle.dk\",\"description\":\"Online Webshop sol & vindenergi\",\"inLanguage\":\"da-DK\",\"publisher\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet","description":"Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer Til bl\u00e6ser p\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\u00f8r til ventilation og solvarme kit","canonical_url":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A","msvalidate.01":"1AF1F6665E665386B40B0E1A7011D221","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/solcelle.dk\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","position":2,"name":"Online solar PV shop \/ Solcelle webshop","item":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/#listItem","name":"Forbrug, LEDlys, k\u00f8l, pumper, ventilation"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/#listItem","position":3,"name":"Forbrug, LEDlys, k\u00f8l, pumper, ventilation","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/#listItem","name":"Solcelleventilation, solvarme og frisk luft"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/#listItem","position":4,"name":"Solcelleventilation, solvarme og frisk luft","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/tilbehoer-til-ventilation\/#listItem","name":"Tilbeh\u00f8r til ventilation og solvarme kit"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/#listItem","name":"Forbrug, LEDlys, k\u00f8l, pumper, ventilation"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/tilbehoer-til-ventilation\/#listItem","position":5,"name":"Tilbeh\u00f8r til ventilation og solvarme kit","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/tilbehoer-til-ventilation\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#listItem","name":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/#listItem","name":"Solcelleventilation, solvarme og frisk luft"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#listItem","position":6,"name":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet","previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/lys-koeleskab-pumper-ventilator\/solvarme-ventilation\/tilbehoer-til-ventilation\/#listItem","name":"Tilbeh\u00f8r til ventilation og solvarme kit"}}]},{"@type":"ItemPage","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#itempage","url":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/","name":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet","description":"Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer Til bl\u00e6ser p\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\u00f8r til ventilation og solvarme kit","inLanguage":"da-DK","isPartOf":{"@id":"https:\/\/solcelle.dk\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2016\/10\/BL\u00c6SERGITTER-med-ring.jpg","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#mainImage","width":250,"height":250,"caption":"BL\u00c6SERGITTER 92 MM 6 RINGS"},"primaryImageOfPage":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#mainImage"},"datePublished":"2016-10-12T12:10:57+01:00","dateModified":"2025-03-15T16:34:47+01:00"},{"@type":"Organization","@id":"https:\/\/solcelle.dk\/wordpress\/#organization","name":"Solcelle.dk, Sol & vind energi","description":"Online Webshop sol & vindenergi","url":"https:\/\/solcelle.dk\/wordpress\/","telephone":"+4541674467","logo":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#organizationLogo","width":144,"height":144,"caption":"Solcelle.dk Online webshop"},"image":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/solcelle.dk\/wordpress\/#website","url":"https:\/\/solcelle.dk\/wordpress\/","name":"Solcelle.dk","description":"Online Webshop sol & vindenergi","inLanguage":"da-DK","publisher":{"@id":"https:\/\/solcelle.dk\/wordpress\/#organization"}}]},"og:locale":"da_DK","og:site_name":"Solcelle.dk | Online Webshop sol &amp; vindenergi","og:type":"article","og:title":"BL\u00c6SERGITTER 60 x 60 MM, 4 RINGS, forkromet","og:description":"Metalisk fingerbeskyttelsen fastg\u00f8res med 4 skruer Til bl\u00e6ser p\u00e5 60x60 MM Antal ring: 4 RINGS Levering: 1-2 dage Tilbeh\u00f8r til ventilation og solvarme kit","og:url":"https:\/\/solcelle.dk\/wordpress\/produkt\/blaesergitter-60-mm-4-rings\/","og:image":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","og:image:secure_url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","article:published_time":"2016-10-12T11:10:57+00:00","article:modified_time":"2025-03-15T15:34:47+00:00"},"aioseo_meta_data":{"post_id":"1310","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 18:49:10","updated":"2025-06-14 20:02:29","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product\/1310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media\/1308"}],"wp:attachment":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media?parent=1310"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_brand?post=1310"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_cat?post=1310"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_tag?post=1310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}