{"id":38244,"date":"2022-05-16T12:32:52","date_gmt":"2022-05-16T11:32:52","guid":{"rendered":"https:\/\/solcelle.dk\/wordpress\/?post_type=product&#038;p=38244"},"modified":"2023-11-10T16:51:36","modified_gmt":"2023-11-10T15:51:36","slug":"stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd","status":"publish","type":"product","link":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/","title":{"rendered":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD"},"content":{"rendered":"<p>STB30NF10T4 N-Kanal, <a href=\"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/\">MOSFET<\/a> transistor, 35 A 100 V, SMD<\/p>\n<p>&#8211; Drain current continuous max. 35 A<br \/>\n&#8211; Drain source voltage max. 100 V<br \/>\n&#8211; Drain source resistor max. 0.045 \u03a9<br \/>\n&#8211; Max. threshold voltage for port 4V<br \/>\n&#8211; Minimum threshold voltage for port 2V<br \/>\n&#8211; Gate source voltage max. \u00b1 20 V<br \/>\n&#8211; Enclosure Type D2PAK<br \/>\n&#8211; Mounting Type Surface Mount<br \/>\nBenantal 3<\/p>\n<p>Channel Form Enhancement<br \/>\nCategory Effect MOSFET<br \/>\nPower consumption max. 115000 mW<br \/>\nConfiguration Single, On-delay time typically 15 ns<br \/>\nNumber of items per chip 1, Width 9.35mm<br \/>\nTurn off delay time typically 45 ns<br \/>\nDimensions 10.4 x 9.35 x 4.6mm<br \/>\nOperating temperature max. 175 \u00b0 C<br \/>\nInput capacity at Vds typically 1180 pF at 25 V<br \/>\nGate charge at Vgs typically 40 nC at 10 V<br \/>\nOperating temperature min. -55 \u00b0 C<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Surface Mount Effect MOSFET<br \/>\nDrain source voltage max. 100 V<br \/>\nDrain source resistor max. 0.045 \u03a9<br \/>\nMax. threshold\u00a0 4V<br \/>\nDelivery: 2-4 days<\/p>\n","protected":false},"featured_media":38254,"template":"","meta":{"_predictive_search_focuskw":"","_ps_exclude_item":""},"product_brand":[],"product_cat":[1580],"product_tag":[1455],"class_list":["post-38244","product","type-product","status-publish","has-post-thumbnail","product_cat-mosfet-transistor","product_tag-mosfet","product_shipping_class-shipping","post","post-with-thumbnail","post-with-thumbnail-large","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A\" \/>\n\t<meta name=\"msvalidate.01\" content=\"1AF1F6665E665386B40B0E1A7011D221\" \/>\n\t<meta name=\"keywords\" content=\"drain current continuous max. 35 a drain source voltage max. 100 v\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"da_DK\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Solcelle.dk | Online Webshop sol &amp; vindenergi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD\" \/>\n\t\t<meta property=\"og:description\" content=\"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-05-16T11:32:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-10T15:51:36+00:00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"position\":2,\"name\":\"Online solar PV shop \\\/ Solcelle webshop\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"name\":\"Elektronik komponenter\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"position\":3,\"name\":\"Elektronik komponenter\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"name\":\"Mosfet Transistor\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"position\":4,\"name\":\"Mosfet Transistor\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#listItem\",\"name\":\"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"name\":\"Elektronik komponenter\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#listItem\",\"position\":5,\"name\":\"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"name\":\"Mosfet Transistor\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#itempage\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/\",\"name\":\"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD\",\"description\":\"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \\u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor\",\"inLanguage\":\"da-DK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/STB100NF03LMOSFET.jpg\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#mainImage\",\"width\":600,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#mainImage\"},\"datePublished\":\"2022-05-16T12:32:52+01:00\",\"dateModified\":\"2023-11-10T16:51:36+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\",\"name\":\"Solcelle.dk, Sol & vind energi\",\"description\":\"Online Webshop sol & vindenergi\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"telephone\":\"+4541674467\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Solcelledk_Logo_144.png\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#organizationLogo\",\"width\":144,\"height\":144,\"caption\":\"Solcelle.dk Online webshop\"},\"image\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"name\":\"Solcelle.dk\",\"description\":\"Online Webshop sol & vindenergi\",\"inLanguage\":\"da-DK\",\"publisher\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD","description":"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor","canonical_url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/","robots":"max-image-preview:large","keywords":"drain current continuous max. 35 a drain source voltage max. 100 v","webmasterTools":{"google-site-verification":"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A","msvalidate.01":"1AF1F6665E665386B40B0E1A7011D221","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/solcelle.dk\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","position":2,"name":"Online solar PV shop \/ Solcelle webshop","item":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","name":"Elektronik komponenter"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","position":3,"name":"Elektronik komponenter","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","name":"Mosfet Transistor"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","position":4,"name":"Mosfet Transistor","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#listItem","name":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","name":"Elektronik komponenter"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#listItem","position":5,"name":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD","previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","name":"Mosfet Transistor"}}]},{"@type":"ItemPage","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#itempage","url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/","name":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD","description":"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor","inLanguage":"da-DK","isPartOf":{"@id":"https:\/\/solcelle.dk\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2022\/05\/STB100NF03LMOSFET.jpg","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#mainImage","width":600,"height":600},"primaryImageOfPage":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#mainImage"},"datePublished":"2022-05-16T12:32:52+01:00","dateModified":"2023-11-10T16:51:36+01:00"},{"@type":"Organization","@id":"https:\/\/solcelle.dk\/wordpress\/#organization","name":"Solcelle.dk, Sol & vind energi","description":"Online Webshop sol & vindenergi","url":"https:\/\/solcelle.dk\/wordpress\/","telephone":"+4541674467","logo":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#organizationLogo","width":144,"height":144,"caption":"Solcelle.dk Online webshop"},"image":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/solcelle.dk\/wordpress\/#website","url":"https:\/\/solcelle.dk\/wordpress\/","name":"Solcelle.dk","description":"Online Webshop sol & vindenergi","inLanguage":"da-DK","publisher":{"@id":"https:\/\/solcelle.dk\/wordpress\/#organization"}}]},"og:locale":"da_DK","og:site_name":"Solcelle.dk | Online Webshop sol &amp; vindenergi","og:type":"article","og:title":"STB30NF10T4 N-Kanal, MOSFET transistor, 35 A 100 V, SMD","og:description":"Surface Mount Effect MOSFET Drain source voltage max. 100 V Drain source resistor max. 0.045 \u03a9 Max. threshold 4V Delivery: 2-4 days Mosfet Transistor","og:url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stb30nf10t4-n-kanal-mosfet-transistor-35-a-100-v-smd\/","og:image":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","og:image:secure_url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","article:published_time":"2022-05-16T11:32:52+00:00","article:modified_time":"2023-11-10T15:51:36+00:00"},"aioseo_meta_data":{"post_id":"38244","title":null,"description":null,"keywords":[{"label":"Drain current continuous max. 35 A Drain source voltage max. 100 V","value":"Drain current continuous max. 35 A Drain source voltage max. 100 V"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-05-16 11:44:27","updated":"2025-06-14 22:44:29","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product\/38244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media\/38254"}],"wp:attachment":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media?parent=38244"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_brand?post=38244"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_cat?post=38244"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_tag?post=38244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}