{"id":38264,"date":"2022-05-16T12:33:01","date_gmt":"2022-05-16T11:33:01","guid":{"rendered":"https:\/\/solcelle.dk\/wordpress\/?post_type=product&#038;p=38264"},"modified":"2024-02-11T14:23:35","modified_gmt":"2024-02-11T13:23:35","slug":"stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22","status":"publish","type":"product","link":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/","title":{"rendered":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22"},"content":{"rendered":"<p>STP35NF10 <a href=\"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/\">MOSFET<\/a> N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22 realized with STMicro-electronics unique STripFET process has specifically been designed to minimize input capacitance and gate charge. It is therefore suitable as primary switch in advanced high-efficiency isolated DC-DC converters for Telecom and Computer application.<\/p>\n<p>&#8211; Polarity N-Channel<br \/>\n&#8211; Technology MOSFET<br \/>\n&#8211; Drain-Source Breakdown Voltage 100V<br \/>\n&#8211; Continuous Drain Current at 25\u00b0C 40A (Tc)<br \/>\n&#8211; Drive Voltage (Max Rds On, Min Rds On) 10V<br \/>\n&#8211; Gate-Source Threshold Voltage 4V @ 250\u03bcA<br \/>\n&#8211; Max Gate Charge 55nC @ 10V<br \/>\n&#8211; Max Input Capacitance 1550pF @ 25V<br \/>\n&#8211; Maximum Gate-Source Voltage \u00b120V<br \/>\n&#8211; Power Dissipation (Max) 115W (Tc)<br \/>\n&#8211; Maximum Rds On at Id,Vgs 35 mOhm @ 17.5A, 10V<br \/>\n&#8211; Temperature Range &#8211; Operating -55\u00b0C to 175\u00b0C (TJ)<br \/>\n&#8211; Mounting Through Hole<br \/>\n&#8211; Case \/ Package TO-220AB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drain-Source Breakdown Voltage 100V<br \/>\n&#8211; Continuous Drain Current at 25\u00b0C 40A (Tc)<br \/>\n&#8211; Drive Voltage (Max Rds On, Min Rds On) 10V<\/p>\n<p>Delivery: 2-4 days<\/p>\n","protected":false},"featured_media":38279,"template":"","meta":{"_predictive_search_focuskw":"","_ps_exclude_item":""},"product_brand":[],"product_cat":[967,1580],"product_tag":[1455,1456],"class_list":["post-38264","product","type-product","status-publish","has-post-thumbnail","product_cat-elektronik-komponenter","product_cat-mosfet-transistor","product_tag-mosfet","product_tag-transistor","product_shipping_class-shipping","post","post-with-thumbnail","post-with-thumbnail-large","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A\" \/>\n\t<meta name=\"msvalidate.01\" content=\"1AF1F6665E665386B40B0E1A7011D221\" \/>\n\t<meta name=\"keywords\" content=\"stmicro-electronics unique stripfet process has specifically\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"da_DK\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Solcelle.dk | Online Webshop sol &amp; vindenergi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22\" \/>\n\t\t<meta property=\"og:description\" content=\"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-05-16T11:33:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-11T13:23:35+00:00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"position\":2,\"name\":\"Online solar PV shop \\\/ Solcelle webshop\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"name\":\"Elektronik komponenter\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"position\":3,\"name\":\"Elektronik komponenter\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"name\":\"Mosfet Transistor\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/online-solar-shop\\\/#listItem\",\"name\":\"Online solar PV shop \\\/ Solcelle webshop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"position\":4,\"name\":\"Mosfet Transistor\",\"item\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#listItem\",\"name\":\"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \\u2126, 40A, TO-22\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/#listItem\",\"name\":\"Elektronik komponenter\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#listItem\",\"position\":5,\"name\":\"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \\u2126, 40A, TO-22\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt-kategori\\\/elektronik-komponenter\\\/mosfet-transistor\\\/#listItem\",\"name\":\"Mosfet Transistor\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#itempage\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/\",\"name\":\"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \\u2126, 40A, TO-22\",\"description\":\"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter\",\"inLanguage\":\"da-DK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/TO220.jpg\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#mainImage\",\"width\":150,\"height\":150,\"caption\":\"TO220.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#mainImage\"},\"datePublished\":\"2022-05-16T12:33:01+01:00\",\"dateModified\":\"2024-02-11T14:23:35+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\",\"name\":\"Solcelle.dk, Sol & vind energi\",\"description\":\"Online Webshop sol & vindenergi\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"telephone\":\"+4541674467\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Solcelledk_Logo_144.png\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#organizationLogo\",\"width\":144,\"height\":144,\"caption\":\"Solcelle.dk Online webshop\"},\"image\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/produkt\\\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/\",\"name\":\"Solcelle.dk\",\"description\":\"Online Webshop sol & vindenergi\",\"inLanguage\":\"da-DK\",\"publisher\":{\"@id\":\"https:\\\/\\\/solcelle.dk\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22","description":"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter","canonical_url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/","robots":"max-image-preview:large","keywords":"stmicro-electronics unique stripfet process has specifically","webmasterTools":{"google-site-verification":"k13Nt5v8l1CdLhjdqMr-8Om0UElG83gV3plAei3Gj5A","msvalidate.01":"1AF1F6665E665386B40B0E1A7011D221","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/solcelle.dk\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","position":2,"name":"Online solar PV shop \/ Solcelle webshop","item":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","name":"Elektronik komponenter"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","position":3,"name":"Elektronik komponenter","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","name":"Mosfet Transistor"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/online-solar-shop\/#listItem","name":"Online solar PV shop \/ Solcelle webshop"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","position":4,"name":"Mosfet Transistor","item":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#listItem","name":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22"},"previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/#listItem","name":"Elektronik komponenter"}},{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#listItem","position":5,"name":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22","previousItem":{"@type":"ListItem","@id":"https:\/\/solcelle.dk\/wordpress\/produkt-kategori\/elektronik-komponenter\/mosfet-transistor\/#listItem","name":"Mosfet Transistor"}}]},{"@type":"ItemPage","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#itempage","url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/","name":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22","description":"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter","inLanguage":"da-DK","isPartOf":{"@id":"https:\/\/solcelle.dk\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2022\/05\/TO220.jpg","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#mainImage","width":150,"height":150,"caption":"TO220.jpg"},"primaryImageOfPage":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#mainImage"},"datePublished":"2022-05-16T12:33:01+01:00","dateModified":"2024-02-11T14:23:35+01:00"},{"@type":"Organization","@id":"https:\/\/solcelle.dk\/wordpress\/#organization","name":"Solcelle.dk, Sol & vind energi","description":"Online Webshop sol & vindenergi","url":"https:\/\/solcelle.dk\/wordpress\/","telephone":"+4541674467","logo":{"@type":"ImageObject","url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#organizationLogo","width":144,"height":144,"caption":"Solcelle.dk Online webshop"},"image":{"@id":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/solcelle.dk\/wordpress\/#website","url":"https:\/\/solcelle.dk\/wordpress\/","name":"Solcelle.dk","description":"Online Webshop sol & vindenergi","inLanguage":"da-DK","publisher":{"@id":"https:\/\/solcelle.dk\/wordpress\/#organization"}}]},"og:locale":"da_DK","og:site_name":"Solcelle.dk | Online Webshop sol &amp; vindenergi","og:type":"article","og:title":"STP35NF10 MOSFET N-CHANNEL 100V, 0.030 \u2126, 40A, TO-22","og:description":"Drain-Source Breakdown Voltage 100V - Continuous Drain Current at 25\u00b0C 40A (Tc) - Drive Voltage (Max Rds On, Min Rds On) 10V Delivery: 2-4 days Elektronik komponenter","og:url":"https:\/\/solcelle.dk\/wordpress\/produkt\/stp35nf10-mosfet-n-channel-100v-0-030-%cf%89-40a-to-22\/","og:image":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","og:image:secure_url":"https:\/\/solcelle.dk\/wordpress\/wp-content\/uploads\/2020\/09\/Solcelledk_Logo_144.png","article:published_time":"2022-05-16T11:33:01+00:00","article:modified_time":"2024-02-11T13:23:35+00:00"},"aioseo_meta_data":{"post_id":"38264","title":null,"description":null,"keywords":[{"label":"STMicro-electronics unique STripFET process has specifically","value":"STMicro-electronics unique STripFET process has specifically"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-05-16 11:45:30","updated":"2025-06-14 22:45:20","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product\/38264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media\/38279"}],"wp:attachment":[{"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/media?parent=38264"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_brand?post=38264"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_cat?post=38264"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/solcelle.dk\/wordpress\/wp-json\/wp\/v2\/product_tag?post=38264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}